{"id":1410,"date":"2020-07-06T09:46:42","date_gmt":"2020-07-06T09:46:42","guid":{"rendered":"https:\/\/test.aisn.pl\/pracownie\/pracownia-angiografii-i-hemodynamiki-regionalny-osrodek-kardiologii-miedziowe-centrum-zdrowia-s-a\/"},"modified":"2025-12-01T12:17:21","modified_gmt":"2025-12-01T11:17:21","slug":"pracownia-angiografii-i-hemodynamiki-regionalny-osrodek-kardiologii-miedziowe-centrum-zdrowia-s-a","status":"publish","type":"pracownie","link":"https:\/\/aisn.pl\/en\/baza_pracowni\/pracownia-angiografii-i-hemodynamiki-regionalny-osrodek-kardiologii-miedziowe-centrum-zdrowia-s-a\/","title":{"rendered":"Pracownia Angiografii i Hemodynamiki Regionalny O\u015brodek Kardiologii Miedziowe Centrum Zdrowia S.A."},"featured_media":0,"template":"","class_list":["post-1410","pracownie","type-pracownie","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/pracownie\/1410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/pracownie"}],"about":[{"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/types\/pracownie"}],"version-history":[{"count":2,"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/pracownie\/1410\/revisions"}],"predecessor-version":[{"id":27374,"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/pracownie\/1410\/revisions\/27374"}],"wp:attachment":[{"href":"https:\/\/aisn.pl\/en\/wp-json\/wp\/v2\/media?parent=1410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}